{"id":38541,"date":"2024-02-03T21:17:44","date_gmt":"2024-02-03T12:17:44","guid":{"rendered":"https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6.jpg"},"modified":"2024-02-03T21:18:03","modified_gmt":"2024-02-03T12:18:03","slug":"6-592","status":"inherit","type":"attachment","link":"https:\/\/osaka.style\/news\/38527\/6-592\/","title":{"rendered":"\u901a\u5929\u95a3\u3067\u300c\u30c0\u30a4\u30d6\uff06\u30a6\u30a9\u30fc\u30af\u300d\u4e8b\u524d\u4f53\u9a13\u4f1a"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-38541","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"150\" src=\"https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6-200x150.jpg\" class=\"attachment-medium size-medium\" alt=\"\u901a\u5929\u95a3\u3067\u300c\u30c0\u30a4\u30d6\uff06\u30a6\u30a9\u30fc\u30af\u300d\u4e8b\u524d\u4f53\u9a13\u4f1a\" \/><\/a><\/p>\n<p>\u901a\u5929\u95a3\uff08\u5927\u962a\u5e02\u6d6a\u901f\u533a\uff09\u30672\u67083\u65e5\u3001\u4eca\u590f\u30aa\u30fc\u30d7\u30f3\u4e88\u5b9a\u306e\u30a2\u30c8\u30e9\u30af\u30b7\u30e7\u30f3\u30f3\u300cDive\uff06Walk\uff08\u30c0\u30a4\u30d6\uff06\u30a6\u30a9\u30fc\u30af\uff09\u300d\u306e\u30e1\u30c7\u30a3\u30a2\u5411\u3051\u4e8b\u524d\u4f53\u9a13\u4f1a\u304c\u884c\u308f\u308c\u305f\u3002<\/p>\n"},"caption":{"rendered":"<p>\u901a\u5929\u95a3\uff08\u5927\u962a\u5e02\u6d6a\u901f\u533a\uff09\u30672\u67083\u65e5\u3001\u4eca\u590f\u30aa\u30fc\u30d7\u30f3\u4e88\u5b9a\u306e\u30a2\u30c8\u30e9\u30af\u30b7\u30e7\u30f3\u30f3\u300cDive\uff06Walk\uff08\u30c0\u30a4\u30d6\uff06\u30a6\u30a9\u30fc\u30af\uff09\u300d\u306e\u30e1\u30c7\u30a3\u30a2\u5411\u3051\u4e8b\u524d\u4f53\u9a13\u4f1a\u304c\u884c\u308f\u308c\u305f\u3002<\/p>\n"},"alt_text":"\u901a\u5929\u95a3\u3067\u300c\u30c0\u30a4\u30d6\uff06\u30a6\u30a9\u30fc\u30af\u300d\u4e8b\u524d\u4f53\u9a13\u4f1a","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":900,"file":"2024\/02\/6.jpg","filesize":621126,"sizes":{"medium":{"file":"6-200x150.jpg","width":200,"height":150,"filesize":29566,"mime_type":"image\/jpeg","source_url":"https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6-200x150.jpg"},"large":{"file":"6-840x630.jpg","width":840,"height":630,"filesize":450912,"mime_type":"image\/jpeg","source_url":"https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6-840x630.jpg"},"thumbnail":{"file":"6-165x165.jpg","width":165,"height":165,"filesize":27061,"mime_type":"image\/jpeg","source_url":"https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6-165x165.jpg"},"medium_large":{"file":"6-768x576.jpg","width":768,"height":576,"filesize":379495,"mime_type":"image\/jpeg","source_url":"https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6-768x576.jpg"},"pclist-main":{"file":"6-410x310.jpg","width":410,"height":310,"filesize":114276,"mime_type":"image\/jpeg","source_url":"https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6-410x310.jpg"},"pclist-sub":{"file":"6-250x250.jpg","width":250,"height":250,"filesize":58927,"mime_type":"image\/jpeg","source_url":"https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6-250x250.jpg"},"sp-main":{"file":"6-750x563.jpg","width":750,"height":563,"filesize":366276,"mime_type":"image\/jpeg","source_url":"https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6-750x563.jpg"},"full":{"file":"6.jpg","width":1200,"height":900,"mime_type":"image\/jpeg","source_url":"https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":38527,"source_url":"https:\/\/osaka.style\/news\/wp-content\/uploads\/2024\/02\/6.jpg","_links":{"self":[{"href":"https:\/\/osaka.style\/news\/wp-json\/wp\/v2\/media\/38541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osaka.style\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/osaka.style\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/osaka.style\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/osaka.style\/news\/wp-json\/wp\/v2\/comments?post=38541"}]}}